<br />
<b>Deprecated</b>:  Use of "self" in callables is deprecated in <b>/home/u902433967/domains/ozinews.in/public_html/english/wp-content/plugins/jnews-essential/lib/vp/autoload.php</b> on line <b>126</b><br />
{"id":14707,"count":1,"description":"","link":"https:\/\/ozinews.in\/english\/tag\/knowledge-of-politics\/","name":"Knowledge of politics","slug":"knowledge-of-politics","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ozinews.in\/english\/wp-json\/wp\/v2\/tags\/14707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ozinews.in\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ozinews.in\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ozinews.in\/english\/wp-json\/wp\/v2\/posts?tags=14707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}